{"id":6524,"date":"2023-02-16T09:30:54","date_gmt":"2023-02-16T08:30:54","guid":{"rendered":"https:\/\/www.confagricoltura.org\/bologna\/?p=6524"},"modified":"2023-02-16T09:30:55","modified_gmt":"2023-02-16T08:30:55","slug":"legge-n-197-del-29-12-2022-legge-di-bilancio-prima-parte","status":"publish","type":"post","link":"https:\/\/www.confagricoltura.org\/bologna\/legge-n-197-del-29-12-2022-legge-di-bilancio-prima-parte\/","title":{"rendered":"Legge n. 197 del \u201c29.12.2022 &#8211; &#8220;LEGGE DI BILANCIO\u201d. Prima Parte."},"content":{"rendered":"\n<p>Riteniamo utile ricapitolare le altre principali misure, di interessa agricolo, inserite nella legge n\u00b0 197 del 29 Dicembre 2022, \u201c<strong>Bilancio di previsione dello Stato per l&#8217;anno finanziario 2023 e bilancio pluriennale per il triennio 2023-2025<\/strong>\u201d.<\/p>\n\n\n\n<p>Per meglio facilitare la lettura di quanto normato all\u2019interno della corposa legge n\u00b0 197\/2022, pubblicheremo articoli&nbsp; specifici a seconda dell\u2019area di competenza: Area Fiscale, Area Lavoro \/ Previdenza, Area Ambiente \/ Sviluppo Sostenibile, Area Politiche di sviluppo economico \/ Credito.<\/p>\n\n\n\n<p>Iniziamo con i provvedimenti riguardanti l\u2019AREA FISCALE.<\/p>\n\n\n\n<p><strong>AREA FISCALE<\/strong><\/p>\n\n\n\n<p><strong>Art. 1, commi 45-51 \u2013 Estensione del credito d\u2019imposta per l\u2019acquisto di carburanti per l\u2019esercizio dell\u2019attivit\u00e0 agricola e della pesca ed crediti di imposta per acquisto gas ed energia elettrica.<\/strong><\/p>\n\n\n\n<p>Il credito per l\u2019acquisto di carburanti per la trazione dei mezzi per le imprese esercenti attivit\u00e0 agricola, della pesca e agromeccanica \u00e8 stato esteso anche al primo trimestre del 2023. Il credito relativo al primo trimestre 2023, pari al 20% delle spese sostenute in tale periodo, \u00e8 utilizzabile in compensazione entro il 31.12.2023 oppure pu\u00f2 essere ceduto. Si ricorda che chi acquista il credito \u00e8 sottoposto alle medesime modalit\u00e0 e al medesimo termine di utilizzo. Per quanto riguarda il credito relativo al terzo trimestre 2022, nella legge di bilancio, \u00e8 stato definito che il termine per l\u2019utilizzo in compensazione o cessione \u00e8 il 31.03.2023.<\/p>\n\n\n\n<p>I crediti relativi alla spesa sostenuta per l\u2019acquisto di gas ed energia elettrica sono stati estesi anche al I trimestre 2023 con le seguenti aliquote:<\/p>\n\n\n\n<p>Energivore: 45%<\/p>\n\n\n\n<p>Non energivore: 35%<\/p>\n\n\n\n<p>Gasivore: 45%<\/p>\n\n\n\n<p>Non gasivore: 45%<\/p>\n\n\n\n<p>I crediti di cui sopra sono utilizzabili entro il 31.12.2023 oppure sono cedibili. Si ricorda che chi acquista il credito \u00e8 sottoposto alle medesime modalit\u00e0 e al medesimo termine di utilizzo.<\/p>\n\n\n\n<p><strong>Art. 1, c. 80 \u2013 Proroga esenzione IRPEF per i redditi dominicali ed agrari di IAP e CD<\/strong><\/p>\n\n\n\n<p>E\u2019 prorogata anche per il 2023 l\u2019esenzione IRPEF sui redditi dominicali e agrari dei terreni posseduti e condotti da coltivatori diretti (CD) e da imprenditori agricoli professionali (IAP), iscritti nella previdenza agricola.<\/p>\n\n\n\n<p><strong>Art. 1, commi 107-109 \u2013 Riapertura dei termini per la rideterminazione dei valori di acquisto di partecipazioni, terreni edificabili e con destinazione agricola<\/strong><\/p>\n\n\n\n<p>\u00c8 stata prorogata la possibilit\u00e0 di rideterminare il valore delle partecipazioni e dei terreni posseduti al di fuori del regime di impresa (nota anche come rivalutazione agevolata). Per fruire dell\u2019agevolazione \u00e8 necessario essere in possesso della perizia che attesti il valore della partecipazione o del terreno e il versamento dell\u2019imposta sostitutiva pari al 16%. L\u2019operazione deve essere conclusa e l\u2019imposta pagata entro il 15.11.2023.<\/p>\n\n\n\n<p><strong>Art. 1, comma 110 \u2013 Agevolazioni ex PPC per l\u2019acquisto di terreni agricoli in favore di giovani di et\u00e0 inferiore ai 40 anni.<\/strong><\/p>\n\n\n\n<p>Le agevolazioni previste con riferimento ad imposte di registro e ipotecaria vengono estese anche agli atti di trasferimento a titolo oneroso ti terreni agricoli e relative pertinenze:<\/p>\n\n\n\n<p>\u00b7&nbsp;In favore di persone fisiche di et\u00e0 inferiore a quarant\u2019anni;<\/p>\n\n\n\n<p>\u00b7&nbsp;Che dichiarino nell\u2019atto di trasferimento di voler conseguire entro 24 mesi l\u2019iscrizione nell\u2019apposita gestione previdenziale ed assistenziale prevista per CD e IAP.<\/p>\n\n\n\n<p><strong>Art. 1, comma 111 \u2013 Agevolazioni per i trasferimenti di fondi rustici nei territori montani<\/strong><\/p>\n\n\n\n<p>Viene prevista l\u2019applicazione delle imposte di registro e ipotecaria in misura fissa e l\u2019esenzione da imposta catastale di bollo per:<\/p>\n\n\n\n<p>\u00b7&nbsp;I trasferimenti della propriet\u00e0 a qualsiasi titolo;<\/p>\n\n\n\n<p>\u00b7&nbsp;Di fondi rustici nei terreni montani;<\/p>\n\n\n\n<p>\u00b7&nbsp;a favore di CD ed IAP iscritti nella relativa gestione previdenziale ed assistenziale, oppure che si impegnano a coltivarlo o condurre direttamente il fondo per un periodo di 5 anni, fornendone apposita dichiarazione in atto.<\/p>\n\n\n\n<p><strong>Art. 1, c. 423 \u2013 Estensione del termine per la consegna al 30 settembre 2023 dei beni d\u2019investimento 4.0 \u201cprenotati\u201d al 31 dicembre 2022<\/strong><\/p>\n\n\n\n<p>Il termine per effettuare gli investimenti in beni strumentali materiali 4.0 per i quali, entro il 31.12.2022, si \u00e8 provveduto a confermare l\u2019ordine e pagare un acconto pari almeno al 20% del totale dell\u2019investimento, \u00e8 prorogato al 30 settembre 2023 (prima 30.06.2023).<\/p>\n\n\n\n<p><strong>Art. 1, commi 30-38 \u2013 Attuazione del Regolamento (UE) 2022\/1854 del Consiglio del 6 ottobre 2022, relativo a un intervento di emergenza per far fronte ai prezzi elevati dell&#8217;energia<\/strong><\/p>\n\n\n\n<p>In attuazione del regolamento (UE)2022\/1854, \u00e8 prevista l\u2019attuazione, per il periodo dal 1.12.2022 al 30.06.2023, di un tetto sui ricavi ottenuti dalla produzione e vendita dell\u2019energia elettrica. La differenza tra il prezzo di riferimento (180 \u20ac \/ MWh) e un valore calcolato sulla base dei prezzi di mercato dovr\u00e0 essere versata al GSE.<\/p>\n\n\n\n<p><strong>Art. 1, commi 39-40 \u2013 Proroga del termine dell\u2019entrata in esercizio degli impianti di produzione di biocarburante avanzato diverso dal biometano, ai fini dell\u2019accesso agli incentivi<\/strong><\/p>\n\n\n\n<p>\u00c8 stato prorogato il termine entro cui devono entrare in esercizio gli impianti di produzione di biocarburi avanzati diversi da biometano per accedere agli incentivi. Il suddetto termine \u00e8 stato spostato al 31.12.2023<\/p>\n\n\n\n<p><strong>Art. 1, commi 54-57 \u2013 Modifiche alla disciplina del regime forfettario (L. n. 190\/2014) e \u201cflat tax\u201d incrementale.<\/strong><\/p>\n\n\n\n<p>\u00c8 elevato il limite dei ricavi o compensi, riferiti all\u2019anno precedente, da euro 65.000 a euro 85.000 per l\u2019accesso al regime forfettario per le persone fisiche esercenti attivit\u00e0 d\u2019impresa arti o professioni, di cui alla L. n. 190\/2014 (c.d. regime di \u201cflat tax\u201d). Inoltre, il predetto regime cessa di avere applicazione dall\u2019anno stesso in cui i ricavi o i compensi percepiti sono superiori a 100.000 euro. In tal caso, sar\u00e0 dovuta l\u2019IVA a partire dalle operazioni che determinano il superamento del suddetto limite. Introdotta la c.d. \u201cflat tax incrementale\u201d secondo cui, per il solo anno 2023, i contribuenti persone fisiche esercenti attivit\u00e0 d\u2019impresa, arti o professioni, diversi da quelli che applicano il regime forfetario \u201cordinario\u201d, potranno avvalersi della \u201ctassa piatta\u201d sull\u2019incremento del reddito conseguito nel 2023, rispetto a quello pi\u00f9 elevato del precedente triennio (2020-2022), al netto di una franchigia pari al 5% di quest\u2019ultimo, nei limiti di un maggior reddito fino a 40.000 euro, che produrr\u00e0 sicuramente un consistente risparmio d\u2019imposta.&nbsp;<\/p>\n\n\n\n<p><strong>Art. 1, commi 414-416 \u2013 Sostegno agli investimenti produttivi delle PMI. Beni Strumentali \u201cNuova Sabatini\u201d e Proroga ultimazione investimenti<\/strong><\/p>\n\n\n\n<p>Al fine di assicurare continuit\u00e0 alle misure di sostegno agli investimenti produttivi delle PMI sono stati stanziati ulteriori 150 milioni di euro per garantire la continuit\u00e0 operativa della misura cd. \u201cNuova Sabatini\u201d (ex art. 2 D.L. 69\/2013). Nello specifico sono assegnati 30 milioni di euro per l\u2019anno 2023 e 40 milioni di euro per ciascuno degli anni dal 2024 al 2026. Inoltre, limitatamente alle iniziative con contratto di finanziamento stipulato dal 1\u00b0 gennaio 2022 al 30 giugno 2023, il termine di dodici mesi per l\u2019ultimazione degli investimenti \u00e8 prorogato per ulteriori 6 mesi.<\/p>\n\n\n\n<p>Altre <strong>tematiche <\/strong>affrontate nella legge di Bilancio sono:<\/p>\n\n\n\n<p>\u00b7&nbsp;posticipata al 1\u00b0 gennaio 2024 la decorrenza dell&#8217;efficacia della c.d. plastic tax e della c.d. sugar tax istituite dalla legge di bilancio 2020 (art. 1, comma 64).<\/p>\n\n\n\n<p>\u00b7&nbsp;sanatoria delle irregolarit\u00e0 formali: si potranno regolarizzare, attraverso il versamento di una somma pari a euro 200 per ciascun periodo d\u2019imposta cui si riferiscono, le irregolarit\u00e0, le infrazioni e l\u2019inosservanza di obblighi o adempimenti, di natura formale, che non rilevano sulla determinazione della base imponibile ai fini delle imposte sui redditi, dell\u2019IVA e dell\u2019IRAP e sul pagamento di tali tributi, commesse fino al 31 ottobre 2022. Il pagamento delle somme dovute per la definizione deve essere eseguito in due rate di pari importo da versare, rispettivamente, entro il 31 marzo 2023 e il 31 marzo 2024 (art. 1, commi 166 \u2013 173).<\/p>\n\n\n\n<p>\u00b7&nbsp;incremento del bonus mobili per il 2023, da euro 5.000 a 8.000 euro (art.1, c. 277)<\/p>\n\n\n\n<p>\u00b7&nbsp;Bonus edilizi: sono state modificate le percentuali di detrazione spettanti per il superbonus, prorogato il bonus barriere 75%, reintrodotta la detrazione dell\u2019IVA sull\u2019acquisto di immobili residenziali ad alta efficienza energetica, prorogate le agevolazioni sull\u2019acquisto di abitazione da parte di under 36 (art. 1, commi 894-895, 10, 76 e 74).<\/p>\n\n\n\n<p>\u00b7&nbsp;Credito di imposta impianti di compostaggio: prorogato fino al 31.12.2023 (art. 1, c. 270)<\/p>\n\n\n\n<p>\u00b7&nbsp;Credito di imposta acquisto materiali riciclati: \u00e8 previsto nella misura del 36 per cento delle spese sostenute e documentate per acquisti di prodotti realizzati con materiali provenienti dalla raccolta differenziata degli imballaggi in plastica ovvero che acquistano imballaggi biodegradabili e compostabili. Il credito d\u2019imposta \u00e8 riconosciuto fino a un importo massimo annuale di 20.000 euro per ciascun beneficiario, nel limite massimo complessivo di spesa di 5 milioni di euro per ciascuno degli anni 2024 e 2025 (art. 1, commi 414 \u2013 416).<\/p>\n\n\n\n<p>\u00b7\u00a0Aliquota iva cessioni pellet: per l\u2019anno 2023 si applica l\u2019aliquota IVA del 10% (art. 1, c. 73).<\/p>\n\n\n\n<p>\u00b7&nbsp;Limite al trasferimento del contante: il limite \u00e8 stato aumentato a 5.000 euro (art. 1, c. 38).<\/p>\n\n\n\n<p>\u00b7&nbsp;Obbligo di accettare pagamenti con pos, che devono essere accettati indipendentemente dall\u2019importo.<\/p>\n\n\n\n<p>\u00b7&nbsp;Modifiche alla disciplina delle accise sui tabacchi (art. 1, c. 122).<\/p>\n\n\n\n<p>I nostri uffici rimangono a disposizione per qualsiasi chiarimento.<\/p>\n\n\n\n<p>(A. Flora)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Riteniamo utile ricapitolare le altre principali misure, di interessa agricolo, inserite nella legge n\u00b0 197 del 29 Dicembre 2022, \u201cBilancio di previsione dello Stato per l&#8217;anno finanziario 2023 e bilancio pluriennale per il triennio 2023-2025\u201d. Per meglio facilitare la lettura di quanto normato all\u2019interno della corposa legge n\u00b0 197\/2022, pubblicheremo articoli&nbsp; specifici a seconda dell\u2019area<\/p>\n","protected":false},"author":7,"featured_media":5892,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wp_mapbox_gl_js_media":[],"footnotes":""},"categories":[23,36,37,25],"tags":[],"class_list":["post-6524","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bologna-agricola-informa","category-informative-fiscali","category-informative-per-associati","category-notiziario-provinciale"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Legge n. 197 del \u201c29.12.2022 - &quot;LEGGE DI BILANCIO\u201d. Prima Parte. - Confagricoltura Bologna<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.confagricoltura.org\/bologna\/legge-n-197-del-29-12-2022-legge-di-bilancio-prima-parte\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Legge n. 197 del \u201c29.12.2022 - &quot;LEGGE DI BILANCIO\u201d. Prima Parte. - Confagricoltura Bologna\" \/>\n<meta property=\"og:description\" content=\"Riteniamo utile ricapitolare le altre principali misure, di interessa agricolo, inserite nella legge n\u00b0 197 del 29 Dicembre 2022, \u201cBilancio di previsione dello Stato per l&#8217;anno finanziario 2023 e bilancio pluriennale per il triennio 2023-2025\u201d. Per meglio facilitare la lettura di quanto normato all\u2019interno della corposa legge n\u00b0 197\/2022, pubblicheremo articoli&nbsp; specifici a seconda dell\u2019area\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.confagricoltura.org\/bologna\/legge-n-197-del-29-12-2022-legge-di-bilancio-prima-parte\/\" \/>\n<meta property=\"og:site_name\" content=\"Confagricoltura Bologna\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-16T08:30:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-16T08:30:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.confagricoltura.org\/bologna\/wp-content\/uploads\/sites\/12\/2021\/11\/Legge-di-Bilancio-2019.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"342\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"confagricolturabologna\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"confagricolturabologna\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.confagricoltura.org\/bologna\/legge-n-197-del-29-12-2022-legge-di-bilancio-prima-parte\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.confagricoltura.org\/bologna\/legge-n-197-del-29-12-2022-legge-di-bilancio-prima-parte\/\"},\"author\":{\"name\":\"confagricolturabologna\",\"@id\":\"https:\/\/www.confagricoltura.org\/bologna\/#\/schema\/person\/277baa2a725fb840103c5f8898746c7f\"},\"headline\":\"Legge n. 197 del \u201c29.12.2022 &#8211; &#8220;LEGGE DI BILANCIO\u201d. Prima Parte.\",\"datePublished\":\"2023-02-16T08:30:54+00:00\",\"dateModified\":\"2023-02-16T08:30:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.confagricoltura.org\/bologna\/legge-n-197-del-29-12-2022-legge-di-bilancio-prima-parte\/\"},\"wordCount\":1378,\"image\":{\"@id\":\"https:\/\/www.confagricoltura.org\/bologna\/legge-n-197-del-29-12-2022-legge-di-bilancio-prima-parte\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.confagricoltura.org\/bologna\/wp-content\/uploads\/sites\/12\/2021\/11\/Legge-di-Bilancio-2019.jpg\",\"articleSection\":[\"Bologna Agricola Informa\",\"Informative Fiscali\",\"Informative per Associati\",\"Notiziario Provinciale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.confagricoltura.org\/bologna\/legge-n-197-del-29-12-2022-legge-di-bilancio-prima-parte\/\",\"url\":\"https:\/\/www.confagricoltura.org\/bologna\/legge-n-197-del-29-12-2022-legge-di-bilancio-prima-parte\/\",\"name\":\"Legge n. 197 del \u201c29.12.2022 - \\\"LEGGE DI BILANCIO\u201d. Prima Parte. - Confagricoltura Bologna\",\"isPartOf\":{\"@id\":\"https:\/\/www.confagricoltura.org\/bologna\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.confagricoltura.org\/bologna\/legge-n-197-del-29-12-2022-legge-di-bilancio-prima-parte\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.confagricoltura.org\/bologna\/legge-n-197-del-29-12-2022-legge-di-bilancio-prima-parte\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.confagricoltura.org\/bologna\/wp-content\/uploads\/sites\/12\/2021\/11\/Legge-di-Bilancio-2019.jpg\",\"datePublished\":\"2023-02-16T08:30:54+00:00\",\"dateModified\":\"2023-02-16T08:30:55+00:00\",\"author\":{\"@id\":\"https:\/\/www.confagricoltura.org\/bologna\/#\/schema\/person\/277baa2a725fb840103c5f8898746c7f\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.confagricoltura.org\/bologna\/legge-n-197-del-29-12-2022-legge-di-bilancio-prima-parte\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.confagricoltura.org\/bologna\/legge-n-197-del-29-12-2022-legge-di-bilancio-prima-parte\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.confagricoltura.org\/bologna\/legge-n-197-del-29-12-2022-legge-di-bilancio-prima-parte\/#primaryimage\",\"url\":\"https:\/\/www.confagricoltura.org\/bologna\/wp-content\/uploads\/sites\/12\/2021\/11\/Legge-di-Bilancio-2019.jpg\",\"contentUrl\":\"https:\/\/www.confagricoltura.org\/bologna\/wp-content\/uploads\/sites\/12\/2021\/11\/Legge-di-Bilancio-2019.jpg\",\"width\":640,\"height\":342},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.confagricoltura.org\/bologna\/legge-n-197-del-29-12-2022-legge-di-bilancio-prima-parte\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.confagricoltura.org\/bologna\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Legge n. 197 del \u201c29.12.2022 &#8211; &#8220;LEGGE DI BILANCIO\u201d. Prima Parte.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.confagricoltura.org\/bologna\/#website\",\"url\":\"https:\/\/www.confagricoltura.org\/bologna\/\",\"name\":\"Confagricoltura Bologna\",\"description\":\"Dalla parte degli Agricoltori\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.confagricoltura.org\/bologna\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.confagricoltura.org\/bologna\/#\/schema\/person\/277baa2a725fb840103c5f8898746c7f\",\"name\":\"confagricolturabologna\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.confagricoltura.org\/bologna\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/edd9a034f35ea6aeadaf9744d1135acc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/edd9a034f35ea6aeadaf9744d1135acc?s=96&d=mm&r=g\",\"caption\":\"confagricolturabologna\"},\"url\":\"https:\/\/www.confagricoltura.org\/bologna\/author\/confagricolturabologna\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Legge n. 197 del \u201c29.12.2022 - \"LEGGE DI BILANCIO\u201d. Prima Parte. - Confagricoltura Bologna","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.confagricoltura.org\/bologna\/legge-n-197-del-29-12-2022-legge-di-bilancio-prima-parte\/","og_locale":"it_IT","og_type":"article","og_title":"Legge n. 197 del \u201c29.12.2022 - \"LEGGE DI BILANCIO\u201d. Prima Parte. - Confagricoltura Bologna","og_description":"Riteniamo utile ricapitolare le altre principali misure, di interessa agricolo, inserite nella legge n\u00b0 197 del 29 Dicembre 2022, \u201cBilancio di previsione dello Stato per l&#8217;anno finanziario 2023 e bilancio pluriennale per il triennio 2023-2025\u201d. Per meglio facilitare la lettura di quanto normato all\u2019interno della corposa legge n\u00b0 197\/2022, pubblicheremo articoli&nbsp; specifici a seconda dell\u2019area","og_url":"https:\/\/www.confagricoltura.org\/bologna\/legge-n-197-del-29-12-2022-legge-di-bilancio-prima-parte\/","og_site_name":"Confagricoltura Bologna","article_published_time":"2023-02-16T08:30:54+00:00","article_modified_time":"2023-02-16T08:30:55+00:00","og_image":[{"width":640,"height":342,"url":"https:\/\/www.confagricoltura.org\/bologna\/wp-content\/uploads\/sites\/12\/2021\/11\/Legge-di-Bilancio-2019.jpg","type":"image\/jpeg"}],"author":"confagricolturabologna","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"confagricolturabologna","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.confagricoltura.org\/bologna\/legge-n-197-del-29-12-2022-legge-di-bilancio-prima-parte\/#article","isPartOf":{"@id":"https:\/\/www.confagricoltura.org\/bologna\/legge-n-197-del-29-12-2022-legge-di-bilancio-prima-parte\/"},"author":{"name":"confagricolturabologna","@id":"https:\/\/www.confagricoltura.org\/bologna\/#\/schema\/person\/277baa2a725fb840103c5f8898746c7f"},"headline":"Legge n. 197 del \u201c29.12.2022 &#8211; &#8220;LEGGE DI BILANCIO\u201d. Prima Parte.","datePublished":"2023-02-16T08:30:54+00:00","dateModified":"2023-02-16T08:30:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.confagricoltura.org\/bologna\/legge-n-197-del-29-12-2022-legge-di-bilancio-prima-parte\/"},"wordCount":1378,"image":{"@id":"https:\/\/www.confagricoltura.org\/bologna\/legge-n-197-del-29-12-2022-legge-di-bilancio-prima-parte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.confagricoltura.org\/bologna\/wp-content\/uploads\/sites\/12\/2021\/11\/Legge-di-Bilancio-2019.jpg","articleSection":["Bologna Agricola Informa","Informative Fiscali","Informative per Associati","Notiziario Provinciale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.confagricoltura.org\/bologna\/legge-n-197-del-29-12-2022-legge-di-bilancio-prima-parte\/","url":"https:\/\/www.confagricoltura.org\/bologna\/legge-n-197-del-29-12-2022-legge-di-bilancio-prima-parte\/","name":"Legge n. 197 del \u201c29.12.2022 - \"LEGGE DI BILANCIO\u201d. Prima Parte. - Confagricoltura Bologna","isPartOf":{"@id":"https:\/\/www.confagricoltura.org\/bologna\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.confagricoltura.org\/bologna\/legge-n-197-del-29-12-2022-legge-di-bilancio-prima-parte\/#primaryimage"},"image":{"@id":"https:\/\/www.confagricoltura.org\/bologna\/legge-n-197-del-29-12-2022-legge-di-bilancio-prima-parte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.confagricoltura.org\/bologna\/wp-content\/uploads\/sites\/12\/2021\/11\/Legge-di-Bilancio-2019.jpg","datePublished":"2023-02-16T08:30:54+00:00","dateModified":"2023-02-16T08:30:55+00:00","author":{"@id":"https:\/\/www.confagricoltura.org\/bologna\/#\/schema\/person\/277baa2a725fb840103c5f8898746c7f"},"breadcrumb":{"@id":"https:\/\/www.confagricoltura.org\/bologna\/legge-n-197-del-29-12-2022-legge-di-bilancio-prima-parte\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.confagricoltura.org\/bologna\/legge-n-197-del-29-12-2022-legge-di-bilancio-prima-parte\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.confagricoltura.org\/bologna\/legge-n-197-del-29-12-2022-legge-di-bilancio-prima-parte\/#primaryimage","url":"https:\/\/www.confagricoltura.org\/bologna\/wp-content\/uploads\/sites\/12\/2021\/11\/Legge-di-Bilancio-2019.jpg","contentUrl":"https:\/\/www.confagricoltura.org\/bologna\/wp-content\/uploads\/sites\/12\/2021\/11\/Legge-di-Bilancio-2019.jpg","width":640,"height":342},{"@type":"BreadcrumbList","@id":"https:\/\/www.confagricoltura.org\/bologna\/legge-n-197-del-29-12-2022-legge-di-bilancio-prima-parte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.confagricoltura.org\/bologna\/"},{"@type":"ListItem","position":2,"name":"Legge n. 197 del \u201c29.12.2022 &#8211; &#8220;LEGGE DI BILANCIO\u201d. Prima Parte."}]},{"@type":"WebSite","@id":"https:\/\/www.confagricoltura.org\/bologna\/#website","url":"https:\/\/www.confagricoltura.org\/bologna\/","name":"Confagricoltura Bologna","description":"Dalla parte degli Agricoltori","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.confagricoltura.org\/bologna\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.confagricoltura.org\/bologna\/#\/schema\/person\/277baa2a725fb840103c5f8898746c7f","name":"confagricolturabologna","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.confagricoltura.org\/bologna\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/edd9a034f35ea6aeadaf9744d1135acc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/edd9a034f35ea6aeadaf9744d1135acc?s=96&d=mm&r=g","caption":"confagricolturabologna"},"url":"https:\/\/www.confagricoltura.org\/bologna\/author\/confagricolturabologna\/"}]}},"_links":{"self":[{"href":"https:\/\/www.confagricoltura.org\/bologna\/wp-json\/wp\/v2\/posts\/6524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.confagricoltura.org\/bologna\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.confagricoltura.org\/bologna\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.confagricoltura.org\/bologna\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.confagricoltura.org\/bologna\/wp-json\/wp\/v2\/comments?post=6524"}],"version-history":[{"count":1,"href":"https:\/\/www.confagricoltura.org\/bologna\/wp-json\/wp\/v2\/posts\/6524\/revisions"}],"predecessor-version":[{"id":6525,"href":"https:\/\/www.confagricoltura.org\/bologna\/wp-json\/wp\/v2\/posts\/6524\/revisions\/6525"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.confagricoltura.org\/bologna\/wp-json\/wp\/v2\/media\/5892"}],"wp:attachment":[{"href":"https:\/\/www.confagricoltura.org\/bologna\/wp-json\/wp\/v2\/media?parent=6524"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.confagricoltura.org\/bologna\/wp-json\/wp\/v2\/categories?post=6524"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.confagricoltura.org\/bologna\/wp-json\/wp\/v2\/tags?post=6524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}